{"id":10813,"date":"2011-10-02T03:00:00","date_gmt":"2011-10-02T03:00:00","guid":{"rendered":"http:\/\/testwordpress.nirmalnagari.org\/smnd\/index.php\/a-noble-inheritance\/"},"modified":"2026-06-21T02:04:58","modified_gmt":"2026-06-21T02:04:58","slug":"una-nobile-eredita","status":"publish","type":"page","link":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/","title":{"rendered":"Una nobile eredit\u00e0"},"content":{"rendered":"\n\n\t<h1>Una nobile eredit\u00e0<\/h1>\n<h2>Discendenti della dinastia Shalivahana<\/h2>\n\t<h4>Esattamente a mezzogiorno del 21 marzo, giorno dell&#8217;equinozio di primavera, del 1923, Nirmala Salve nacque a Chindwara, una citt\u00e0 nel cuore dell&#8217;India. Le nobili qualit\u00e0 dei suoi antenati si mostrarono nel carattere della giovane Nirmala sin dalla pi\u00f9 tenera et\u00e0<\/h4>\n\t\t<img decoding=\"async\" data-spai-excluded=\"true\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/PWHnhJCTwLA\/maxresdefault.jpg\"  \/><button aria-label=\"Play\"><\/button><meta itemprop=\"embedUrl\" content=\"https:\/\/www.youtube.com\/embed\/PWHnhJCTwLA\"\/><meta itemprop=\"name\" content=\"Family, Birth And Education\"\/><meta itemprop=\"description\" content=\"Shri Mataji&#039;s parents were educated and enlightened people. She speaks about their encounter with a tiger just before her birth. Shri Mataji&#039;s mother felt great compassion towards this animal. The ease and purity of the birth gave them cause to call their child Nirmala, meaning &#039;immaculate.&#039; They felt she was certain to do something great. Her father guided her to an understanding of humans and encouraged her to give Realization. More videos at: http:\/\/ShriMataji.org ~ A Life Dedicated to Humanity ~\"\/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/PWHnhJCTwLA\/0.jpg\"\/><meta itemprop=\"duration\" content=\"PT5M31S\"\/><meta itemprop=\"uploadDate\" content=\"2020-07-20T00:16:36Z\"\/>\t\n\t<p>La nonna paterna, Sakhubai Salve, mostr\u00f2 le virt\u00f9 e le doti di coraggio che avevano caratterizzato la famiglia nei secoli. Nel 1883, mentre si trovava nelle ultime fasi della gravidanza, Sakhubai perse il marito in circostanze tragiche. Minacciata dai parenti (che non tolleravano il fatto che lui e la sua famiglia fossero cristiani), nonostante la minaccia incombente dei monsoni e del vicino fiume in piena, prese i suoi quattro figli e se ne and\u00f2 in tarda notte.<\/p>\nSakhubai aveva una fede tale che, nonostante le sue condizioni fisiche, il sari lungo nove metri, la pioggia battente e il fiume in piena, riusc\u00ec ad attraversarlo con i suoi figli, per poi percorrere a piedi otto chilometri fino alla stazione ferroviaria pi\u00f9 vicina. All&#8217;alba, salirono su un treno diretto a Ujjain, la citt\u00e0 dove viveva il fratello di Sakhubai. In queste difficili circostanze nacque Prasad Rao Salve, il padre di Shri Mataji.\n\t<p>Sakhubai e i suoi figli dovettero adattarsi da una vita di ricchezza e agi a una di estrema frugalit\u00e0. L&#8217;istruzione dei figli, tuttavia, era fondamentale per Sakhubai, che instill\u00f2 in loro uno spirito di sacrificio e dedizione. Quando in casa non c&#8217;era pi\u00f9 cherosene, continuavano a studiare sotto i lampioni.<\/p>\n<p>Prasad Rao, il pi\u00f9 giovane, era uno studente particolarmente brillante e ricevette borse di studio durante tutto il suo percorso accademico. Studi\u00f2 legge ed entr\u00f2 a far parte di un noto studio legale nella citt\u00e0 di Chhindwara. Si spos\u00f2 poco dopo, ma purtroppo rimase vedovo a 37 anni, con cinque figli. Sebbene riluttante, alla fine fu convinto dai parenti a risposarsi, preoccupato per il benessere dei figli.<\/p>\n<p>C&#8217;era una giovane donna di Nagpur di nome Cornelia Karuna Jadhav, la prima donna in India a conseguire una laurea con lode in matematica. Era anche un&#8217;esperta di sanscrito e conosceva a fondo l&#8217;antica cultura indiana. Proprio per la sua elevata istruzione, fu difficile per suo padre trovarle un marito con qualifiche accademiche almeno pari, se non superiori.<\/p>\n<p>Tramite amici comuni, Prasad Rao invi\u00f2 una proposta di matrimonio a Cornelia e a suo padre. Non fu una decisione facile per lei accettare la proposta di un vedovo con cinque figli. Tuttavia, fu colpita dalla sua intelligenza e dalla sua fede in Dio, e prov\u00f2 una profonda compassione per i suoi figli, rimasti orfani di madre in tenera et\u00e0. Si sposarono il 21 giugno 1920.<\/p>\n\t<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\"> I miei antenati regnarono in questo luogo, che era la capitale degli Shalivahanas, chiamata Prathishthan, o pi\u00f9 semplicemente Paithan. Furono i governanti per migliaia di anni.<\/p>\n<br \/>\nFurono loro a fondare la dinastia Shalivahan; in realt\u00e0, si definivano Sathvahan, che significa sette Vahana (veicoli). Rappresentavano i sette Vahana dei sette chakra. \u00c8 sorprendente quanto tutto ci\u00f2 sia Sahaj (semplice, spontaneo).<\/div><\/div>\n\t<p>Prasad Rao e Cornelia condividevano un profondo amore per il loro paese, la sua grande tradizione spirituale e i suoi valori. La loro figlia Nirmala aveva solo due anni nel 1925 quando incontrarono Mahatma Gandhi per la prima volta, e questo incontro ebbe un enorme impatto su di loro. Riconobbero e condivisero la sua visione di un&#8217;India libera da raggiungere attraverso la lotta non violenta.<\/p>\n<p>Nonostante Prasad Rao avesse ricevuto un titolo nobiliare dagli inglesi e fosse cristiano (il che comportava molti privilegi durante il periodo del dominio britannico), lui e sua moglie non esitarono ad unirsi al movimento, rendendo chiara la loro posizione &#8211; arrivando persino a bruciare i loro abiti di fabbricazione straniera nella piazza principale di Nagpur. A causa del loro coinvolgimento nella lotta per l&#8217;indipendenza, furono entrambi incarcerati diverse volte e imposero come regola familiare che nessuno dovesse versare lacrime per loro. La libert\u00e0 dell&#8217;India era la cosa pi\u00f9 importante e il sacrificio personale era la regola, non l&#8217;eccezione.<\/p>\n\t<div class=\"epyt-video-wrapper\"><div  data-ep-a=\"fadeIn\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_85754\"  width=\"3840\" height=\"2160\"  data-origwidth=\"3840\" data-origheight=\"2160\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/WOPg1lrL1ps?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=1&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade  no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/WOPg1lrL1ps\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><span itemprop=\"video\" itemscope itemtype=\"http:\/\/schema.org\/VideoObject\"><meta itemprop=\"embedUrl\" content=\"https:\/\/www.youtube.com\/embed\/WOPg1lrL1ps\"><meta itemprop=\"name\" content=\"An Ideal Father And Leader\"><meta itemprop=\"description\" content=\"A learned man who fought for his people, Shri Mataji remembers her own father, Prasad Rao Salve. She describes a brilliant man of principle and ideals. He was a leader in the fight for Indian independence, willing to go to jail for a just cause -- once for more than three years. The immense sacrifices he made, inspired Shri Mataji forward in her life&#039;s work, giving her a sense of right and wrong. More videos at: http:\/\/ShriMataji.org ~ A Life Dedicated to Humanity ~\"><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/WOPg1lrL1ps\/0.jpg\"><meta itemprop=\"duration\" content=\"PT2M31S\"><meta itemprop=\"uploadDate\" content=\"2020-07-20T00:13:01Z\"><\/span>\n\t<p>Poich\u00e9 i suoi genitori erano spesso assenti o in prigione, Shri Mataji si assunse la responsabilit\u00e0 della gestione della casa affinch\u00e9 i suoi fratelli maggiori potessero continuare gli studi senza interruzioni. All&#8217;epoca aveva otto anni.<\/p>\n<p>Alcuni anni dopo, Shri Mataji raggiunse l&#8217;et\u00e0 per unirsi alla lotta per la libert\u00e0, incoraggiando i suoi compagni di studi a fare lo stesso. Anche lei fu imprigionata e persino torturata dagli inglesi. Ma il suo spirito non fu indebolito da questa esperienza. Per tutta la vita, continu\u00f2 a incarnare gli eterni valori dei suoi nobili antenati: coraggio, abnegazione e compassione.<\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2018\/07\/media_originals\/images\/shri-mataji-and-family\/shri-mataji-nirmala-devi-and-family.jpg\" alt=\"shri-mataji-nirmala-devi-and-family\" height=\"1045\" width=\"1500\" title=\"shri-mataji-nirmala-devi-and-family\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<hr \/>\n<h3>H. P. Salve, &#8216;Le mie memorie&#8217; Nuova Delhi: Life Eternal Trust, 2000.<\/h3>\n\n","protected":false},"excerpt":{"rendered":"<p>Una nobile eredit\u00e0 Discendenti della dinastia Shalivahana Esattamente a mezzogiorno del 21 marzo, giorno dell&#8217;equinozio di primavera, del 1923, Nirmala Salve nacque a Chindwara, una citt\u00e0 nel cuore dell&#8217;India. Le nobili qualit\u00e0 dei suoi antenati si mostrarono nel carattere della giovane Nirmala sin dalla pi\u00f9 tenera et\u00e0 La nonna paterna, Sakhubai Salve, mostr\u00f2 le virt\u00f9&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/\">Read more<\/a><\/p>\n","protected":false},"author":13,"featured_media":9512,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pro\/page-templates\/full-width-page.php","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","advanced-sidebar-menu\/link-title":"","advanced-sidebar-menu\/exclude-page":false},"class_list":["post-10813","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una nobile eredit\u00e0 - TEST - SMND<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nobile eredit\u00e0 - TEST - SMND\" \/>\n<meta property=\"og:description\" content=\"Una nobile eredit\u00e0 Discendenti della dinastia Shalivahana Esattamente a mezzogiorno del 21 marzo, giorno dell&#8217;equinozio di primavera, del 1923, Nirmala Salve nacque a Chindwara, una citt\u00e0 nel cuore dell&#8217;India. Le nobili qualit\u00e0 dei suoi antenati si mostrarono nel carattere della giovane Nirmala sin dalla pi\u00f9 tenera et\u00e0 La nonna paterna, Sakhubai Salve, mostr\u00f2 le virt\u00f9&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/\" \/>\n<meta property=\"og:site_name\" content=\"TEST - SMND\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shrimataji\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-21T02:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/7_Banner-Family_NobleInheritance-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@shrimataji\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/\",\"name\":\"Una nobile eredit\u00e0 - TEST - SMND\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/7_Banner-Family_NobleInheritance-scaled.jpg\",\"datePublished\":\"2011-10-02T03:00:00+00:00\",\"dateModified\":\"2026-06-21T02:04:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/7_Banner-Family_NobleInheritance-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/7_Banner-Family_NobleInheritance-scaled.jpg\",\"width\":2560,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/una-nobile-eredita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/uk\\\/home-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nobile eredit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/\",\"name\":\"Shri Mataji Nirmala Devi\",\"description\":\"A Life Dedicated to Humanity\",\"publisher\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\",\"name\":\"Nirmala Shrivastava\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nirmala Shrivastava\"},\"logo\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\"},\"sameAs\":[\"https:\\\/\\\/shrimataji.org\\\/test\",\"https:\\\/\\\/www.facebook.com\\\/shrimataji\",\"https:\\\/\\\/x.com\\\/shrimataji\",\"https:\\\/\\\/www.youtube.com\\\/@Shri_Mataji_Nirmala_Devi\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nobile eredit\u00e0 - TEST - SMND","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Una nobile eredit\u00e0 - TEST - SMND","og_description":"Una nobile eredit\u00e0 Discendenti della dinastia Shalivahana Esattamente a mezzogiorno del 21 marzo, giorno dell&#8217;equinozio di primavera, del 1923, Nirmala Salve nacque a Chindwara, una citt\u00e0 nel cuore dell&#8217;India. Le nobili qualit\u00e0 dei suoi antenati si mostrarono nel carattere della giovane Nirmala sin dalla pi\u00f9 tenera et\u00e0 La nonna paterna, Sakhubai Salve, mostr\u00f2 le virt\u00f9&hellip; Read more","og_url":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/","og_site_name":"TEST - SMND","article_publisher":"https:\/\/www.facebook.com\/shrimataji","article_modified_time":"2026-06-21T02:04:58+00:00","og_image":[{"width":2560,"height":905,"url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/7_Banner-Family_NobleInheritance-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@shrimataji","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/","url":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/","name":"Una nobile eredit\u00e0 - TEST - SMND","isPartOf":{"@id":"https:\/\/shrimataji.org\/test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/#primaryimage"},"image":{"@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/#primaryimage"},"thumbnailUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/7_Banner-Family_NobleInheritance-scaled.jpg","datePublished":"2011-10-02T03:00:00+00:00","dateModified":"2026-06-21T02:04:58+00:00","breadcrumb":{"@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/#primaryimage","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/7_Banner-Family_NobleInheritance-scaled.jpg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/7_Banner-Family_NobleInheritance-scaled.jpg","width":2560,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/shrimataji.org\/test\/it\/una-nobile-eredita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shrimataji.org\/test\/uk\/home-en\/"},{"@type":"ListItem","position":2,"name":"Una nobile eredit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/shrimataji.org\/test\/#website","url":"https:\/\/shrimataji.org\/test\/","name":"Shri Mataji Nirmala Devi","description":"A Life Dedicated to Humanity","publisher":{"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shrimataji.org\/test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1","name":"Nirmala Shrivastava","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","width":"1024","height":"1024","caption":"Nirmala Shrivastava"},"logo":{"@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg"},"sameAs":["https:\/\/shrimataji.org\/test","https:\/\/www.facebook.com\/shrimataji","https:\/\/x.com\/shrimataji","https:\/\/www.youtube.com\/@Shri_Mataji_Nirmala_Devi\/featured"]}]}},"lang":"it","translations":{"it":10813,"ur":37380,"en":434,"am":17951,"th":19872,"hu":19426,"sq":18352,"zh":17249,"hi":7323,"tr":10127,"pt":10344,"pl":10478,"de":10617,"fr":10715,"es":10911,"ja":11208,"ru":11396,"bn":11588,"te":11696,"sw":11819,"he":11967,"sk":12356,"fa":12454,"fi":12552,"bg":13510,"ro":14585,"cs":14778,"nl":16512,"ku":16672,"ar":16848,"el":17659,"be":18559,"kn":18833,"mr":20236,"uk":20528,"ml":20827,"ta":22667,"sv":22940,"gu":28788,"pa":28946,"fil":29386,"da":37694,"nn":38246},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/10813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/comments?post=10813"}],"version-history":[{"count":0,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/10813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media\/9512"}],"wp:attachment":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media?parent=10813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}