{"id":10824,"date":"2022-02-25T04:05:58","date_gmt":"2022-02-25T04:05:58","guid":{"rendered":"https:\/\/test.shrimataji.org\/?page_id=6476"},"modified":"2026-06-21T02:04:56","modified_gmt":"2026-06-21T02:04:56","slug":"chakra-e-qualita","status":"publish","type":"page","link":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/","title":{"rendered":"Chakra e Qualit\u00e0"},"content":{"rendered":"\n\n\t<h1><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a>Chakra e Qualit\u00e0<\/h1>\n<h2>Le ruote della vita<\/h2>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">I Chakra sono creati dai cinque elementi; terra, acqua, aria, fuoco ed etere.<\/div><\/div>\n\t<h4>Shri Mataji ha spiegato ai ricercatori come si possono effettivamente sentire i centri sottili (chakra) sia nel corpo che nelle estremit\u00e0, come la punta delle dita delle mani e dei piedi. A seconda dello stato della nostra psiche umana, si possono provare sensazioni diverse, dal caldo, al freddo, al formicolio o pesantezza fisica. Lei ha pazientemente decodificato ognuna di queste sensazioni che i ricercatori sperimentavano in sua presenza in un problema specifico che li stava colpendo a livello fisico, mentale, emotivo e spirituale. Ha sottolineato che questa esperienza spirituale yogica \u00e8 molto ben descritta in varie scritture del mondo, specialmente nei versetti del Sacro Corano.<\/h4>\n\t<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">Lo chiamano Kiyama[<a href=\"#citation-note-1\">1<\/a>] nel Corano, dove si dice che le tue mani parleranno e ti diranno tutto su di te e sugli altri. Questo \u00e8 esattamente ci\u00f2 che accade sulla punta delle tue dita, potete sentire i vostri centri e anche quelli degli altri. In questo modo, sviluppate la conoscenza del S\u00e9 e diventate anche collettivamente coscienti.<\/div><\/div>\n<p>Si possono visualizzare i Chakra come un fascio di lingue di fuoco o anche petali di loto. Ogni Chakra ha un numero diverso di petali corrispondente al numero di sottoplessi all&#8217;interno del plesso nervoso. I plessi nervosi regolano il flusso di informazioni all&#8217;interno del nostro corpo e del cervello che facilita un funzionamento armonioso del nostro essere.Sono la radice di tutte le nostre attivit\u00e0 fisiche, mentali ed emotive. Pertanto, ogni Chakra \u00e8 associato a determinati tratti fisici, mentali ed emotivi. Quando sperimentiamo disturbi a livello mentale, emotivo o fisico, ci\u00f2 \u00e8 dovuto a dei blocchi o ostacoli a livello sottile in questi Chakra.<\/p>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">L&#8217;energia sottile entra attraverso il centro del cervello (Sahasrara Brahmarandhra) e scende in altri sei centri lungo la sua strada. La manifestazione grossolana di questa energia sottile, nel canale Sushumna della spina dorsale, \u00e8 chiamata sistema nervoso parasimpatico. I centri dei Chakra sono espressi come plessi al di fuori del midollo spinale. Sorprendentemente, il numero di plessi e sottoplessi all&#8217;esterno \u00e8 lo stesso di quello dei chakra e dei loro petali all&#8217;interno del midollo spinale.<\/div><\/div>\n<p>L&#8217;estensione periferica del nostro sistema nervoso coincide con l&#8217;estensione periferica del nostro corpo sottile, che consente una correlazione diretta tra i chakra all&#8217;interno del midollo spinale e le estremit\u00e0 corrispondenti sulle nostre mani e piedi. Se si conosce la corretta decodifica di queste posizioni nel nostro corpo e dei loro corrispondenti centri sottili (Chakra) si pu\u00f2 facilmente padroneggiare il proprio essere fisico, mentale, emotivo e spirituale. Non si \u00e8 pi\u00f9 separati dalla realt\u00e0 assoluta universale, ma ci si pu\u00f2 distaccare dalle illusioni delle realt\u00e0 percepite attraverso la conoscenza di s\u00e9.<\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2026\/05\/IT-Chakras-Qualities-scaled.png\" alt=\"IT-Chakras &amp; Qualities\" height=\"2560\" width=\"2095\" title=\"IT-Chakras &amp; Qualities\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<p>I centri del nostro sistema sottile non solo regolano il nostro benessere fisico, mentale ed emotivo, ma contribuiscono anche a plasmare la nostra personalit\u00e0. Si possono considerare come un deposito dei nostri tratti caratteriali. Man mano che evolviamo, maturiamo e cresciamo, questi tratti si manifestano nella nostra vita, a volte consciamente e spesso inconsciamente. Pensate a quante volte avete sentito l&#8217;impulso di aiutare qualcuno, di essere gentili o generosi in una determinata situazione. Da dove provengono questi sentimenti? Le antiche culture orientali, come quelle cinese e indiana, che vivevano basandosi sulla conoscenza del sistema sottile, fondavano le loro societ\u00e0 sui valori pi\u00f9 elevati della vita spirituale, sul Dharma. Dharma, nell&#8217;antica lingua sanscrita, significa &#8220;retto codice di condotta&#8221;, un codice in armonia con lo spirito universale. Un&#8217;analogia potrebbe essere fatta con i Dieci Comandamenti tramandati a Mos\u00e8. In effetti, in molte delle antiche religioni, culture e tradizioni del mondo si possono trovare altri esempi di questo codice di condotta interiore universale.<\/p>\n\t\t<iframe loading=\"lazy\" title=\"Chakras - The Subtle Centers\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.youtube.com\/embed\/8_ocwivaNcc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\t\n\t<p>Sulla base della conoscenza condivisa da Shri Mataji, le sezioni seguenti descrivono in dettaglio ogni Chakra ed evidenziano i tratti innati della personalit\u00e0 basati sul principio primordiale dei centri sottili. Alcune delle qualit\u00e0 di questi centri si dispiegano nella nostra consapevolezza umana fin dal momento della nostra nascita. Le qualit\u00e0 sottili superiori di questi centri si manifestano pienamente dopo la nostra Realizzazione del S\u00e9, attraverso il risveglio della <a href=\"https:\/\/shrimataji.org\/test\/it\/kundalini-it\/\" target=\"_blank\" rel=\"noopener\"><u>Kundalini<\/u><\/a>.<\/p>\n<p>Usando questa sottile conoscenza dei diversi centri, possiamo aiutare noi stessi a vivere in armonia con la nostra innata natura spirituale e con i nostri simili.<\/p>\n\t<hr \/>\n<a id=citation-note-1><\/a><br \/>\n\u00a0[1] si riferisce ad Al-Qiyama o Al-Qiyamah, noto come il giorno della resurrezione nel Corano\n\n","protected":false},"excerpt":{"rendered":"<p>Chakra e Qualit\u00e0 Le ruote della vita Shri Mataji ha spiegato ai ricercatori come si possono effettivamente sentire i centri sottili (chakra) sia nel corpo che nelle estremit\u00e0, come la punta delle dita delle mani e dei piedi. A seconda dello stato della nostra psiche umana, si possono provare sensazioni diverse, dal caldo, al freddo,&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/\">Read more<\/a><\/p>\n","protected":false},"author":13,"featured_media":9250,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","advanced-sidebar-menu\/link-title":"","advanced-sidebar-menu\/exclude-page":false},"class_list":["post-10824","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chakra e Qualit\u00e0 - TEST - SMND<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chakra e Qualit\u00e0 - TEST - SMND\" \/>\n<meta property=\"og:description\" content=\"Chakra e Qualit\u00e0 Le ruote della vita Shri Mataji ha spiegato ai ricercatori come si possono effettivamente sentire i centri sottili (chakra) sia nel corpo che nelle estremit\u00e0, come la punta delle dita delle mani e dei piedi. A seconda dello stato della nostra psiche umana, si possono provare sensazioni diverse, dal caldo, al freddo,&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/\" \/>\n<meta property=\"og:site_name\" content=\"TEST - SMND\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shrimataji\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-21T02:04:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/15_Banner-SY-ChakrasQualities-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@shrimataji\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/\",\"name\":\"Chakra e Qualit\u00e0 - TEST - SMND\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/15_Banner-SY-ChakrasQualities-scaled.jpg\",\"datePublished\":\"2022-02-25T04:05:58+00:00\",\"dateModified\":\"2026-06-21T02:04:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/15_Banner-SY-ChakrasQualities-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/15_Banner-SY-ChakrasQualities-scaled.jpg\",\"width\":2560,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/it\\\/chakra-e-qualita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/uk\\\/home-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chakra e Qualit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/\",\"name\":\"Shri Mataji Nirmala Devi\",\"description\":\"A Life Dedicated to Humanity\",\"publisher\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\",\"name\":\"Nirmala Shrivastava\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nirmala Shrivastava\"},\"logo\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\"},\"sameAs\":[\"https:\\\/\\\/shrimataji.org\\\/test\",\"https:\\\/\\\/www.facebook.com\\\/shrimataji\",\"https:\\\/\\\/x.com\\\/shrimataji\",\"https:\\\/\\\/www.youtube.com\\\/@Shri_Mataji_Nirmala_Devi\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chakra e Qualit\u00e0 - TEST - SMND","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Chakra e Qualit\u00e0 - TEST - SMND","og_description":"Chakra e Qualit\u00e0 Le ruote della vita Shri Mataji ha spiegato ai ricercatori come si possono effettivamente sentire i centri sottili (chakra) sia nel corpo che nelle estremit\u00e0, come la punta delle dita delle mani e dei piedi. A seconda dello stato della nostra psiche umana, si possono provare sensazioni diverse, dal caldo, al freddo,&hellip; Read more","og_url":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/","og_site_name":"TEST - SMND","article_publisher":"https:\/\/www.facebook.com\/shrimataji","article_modified_time":"2026-06-21T02:04:56+00:00","og_image":[{"width":2560,"height":905,"url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/15_Banner-SY-ChakrasQualities-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@shrimataji","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/","url":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/","name":"Chakra e Qualit\u00e0 - TEST - SMND","isPartOf":{"@id":"https:\/\/shrimataji.org\/test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/#primaryimage"},"image":{"@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/#primaryimage"},"thumbnailUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/15_Banner-SY-ChakrasQualities-scaled.jpg","datePublished":"2022-02-25T04:05:58+00:00","dateModified":"2026-06-21T02:04:56+00:00","breadcrumb":{"@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/#primaryimage","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/15_Banner-SY-ChakrasQualities-scaled.jpg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/15_Banner-SY-ChakrasQualities-scaled.jpg","width":2560,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/shrimataji.org\/test\/it\/chakra-e-qualita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shrimataji.org\/test\/uk\/home-en\/"},{"@type":"ListItem","position":2,"name":"Chakra e Qualit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/shrimataji.org\/test\/#website","url":"https:\/\/shrimataji.org\/test\/","name":"Shri Mataji Nirmala Devi","description":"A Life Dedicated to Humanity","publisher":{"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shrimataji.org\/test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1","name":"Nirmala Shrivastava","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","width":"1024","height":"1024","caption":"Nirmala Shrivastava"},"logo":{"@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg"},"sameAs":["https:\/\/shrimataji.org\/test","https:\/\/www.facebook.com\/shrimataji","https:\/\/x.com\/shrimataji","https:\/\/www.youtube.com\/@Shri_Mataji_Nirmala_Devi\/featured"]}]}},"lang":"it","translations":{"it":10824,"ur":37400,"en":6476,"am":17971,"th":19901,"hu":19446,"sq":18372,"zh":17269,"hi":7374,"tr":10139,"pt":10355,"de":10628,"fr":10726,"es":10922,"ja":11219,"ru":11407,"bn":11599,"te":11707,"sw":11830,"he":11978,"el":12269,"sk":12367,"fa":12465,"fi":12563,"bg":13378,"ro":14452,"cs":14645,"nl":16532,"ku":16692,"ar":16868,"be":18579,"kn":18853,"mr":20265,"uk":20557,"ml":20856,"ta":22687,"sv":22960,"gu":28808,"pa":28966,"fil":29406,"da":37714,"pl":37931,"nn":38266},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/10824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/comments?post=10824"}],"version-history":[{"count":0,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/10824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media\/9250"}],"wp:attachment":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media?parent=10824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}