{"id":16523,"date":"2022-01-29T09:56:43","date_gmt":"2022-01-29T09:56:43","guid":{"rendered":"https:\/\/test.shrimataji.org\/?page_id=6391"},"modified":"2025-11-19T10:42:34","modified_gmt":"2025-11-19T10:42:34","slug":"spirituele-groei","status":"publish","type":"page","link":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/","title":{"rendered":"Spirituele groei"},"content":{"rendered":"\n\n\t<h1>Spirituele groei<\/h1>\n<h2>De illusies van het leven overstijgen<\/h2>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\"> Nu is het tijd om op te stijgen. &#8230; En je begint de koele bries te voelen die uit je hoofd komt. Je voelt de koele bries zelfs in je hand. <\/div><\/div>\n<h4>Het belangrijkste doel van zelfrealisatie is het bereiken van een perfecte staat van evenwicht waarin we voortdurend kunnen opstijgen naar hogere bewustzijnsgebieden. Sahaja Yoga meditatie helpt ons om grote hoogten in ons spirituele bewustzijn te bereiken, waarvan de voordelen worden weerspiegeld in ons dagelijks leven, gezin, werk en samenleving. Het is een belangrijke mijlpaal die we moeten bereiken om een duurzaam leven voor onszelf en onze planeet Aarde tot stand te brengen.<\/h4>\n<p>De grootste uitdaging voor onze spirituele groei is het overwinnen van dit vergankelijke leven, vaak het illusoire leven genoemd, dat we zien als onze dagelijkse realiteit.\u00a0Oude geschriften beschrijven dat onze wisselende\u00a0 ervaringen in dit vergankelijke leven de bron zijn van ons ongeluk: ons bewustzijn slingert heen en weer tussen opwinding en depressie, plezier en pijn, winst en verlies. Ze adviseren daarom een pad van ascese en meditatie te volgen, om innerlijke vrede en troost te vinden in een hoger spiritueel bewustzijn.<\/p>\n<p>Dit verklaart waarom veel zoekers afstand proberen te doen van de wereld en proberen aan haar chaos te ontsnappen door de afzondering op te zoeken van afgelegen plaatsen zoals de Himalaya, in de overtuiging dat ze daar nirvana of spirituele bevrijding zullen bereiken. Hoewel een handvol fervente zoekers verlichting vindt onder begeleiding van een zelf-gerealiseerde guru, keren velen teleurgesteld en met lege handen terug, zelfs na jaren van een hard ascetisch leven en rigoureuze beoefening van\u00a0yoga-meditatie.<\/p>\n<p>Sahaja Yoga meditatie vereist geen strenge ascetische levensstijl of terugtrekking uit de samenleving. Het is het meest geschikt om te beoefenen als gezinshoofd of als gewone burger die midden in de samenleving leeft. In feite bieden juist de uitdagingen in ons dagelijks leven een gezonde basis om onze staat van spirituele groei te testen, die we bereiken door de beoefening van Sahaja Yoga meditatie.<\/p>\n<p>Door onze zelfrealisatie te bewerkstelligen door middel van Sahaja Yoga meditatie, realiseren we onze ware aard als zuivere universele geest. Met dit bewustzijn, samen met de hulpmiddelen die Sahaja Yoga ons aanreikt, zijn we in staat getuige te zijn van de onrust van het leven, ons te onthechten van de identificatie met problemen en obstakels, en te zien dat veel van wat wij als een &#8216;leven&#8217; beschouwen, een resultaat is van onze eigen, zelfopgelegde manier van denken en onze verwachtingen, en dus van voorbijgaande aard.<\/p>\n<div class=\"epyt-video-wrapper\"><div  data-ep-a=\"fadeIn\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_50725\"  width=\"3840\" height=\"2160\"  data-origwidth=\"3840\" data-origheight=\"2160\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/L9AKl8ypUcE?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=1&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade  no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/L9AKl8ypUcE\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><span itemprop=\"video\" itemscope itemtype=\"http:\/\/schema.org\/VideoObject\"><meta itemprop=\"embedUrl\" content=\"https:\/\/www.youtube.com\/embed\/L9AKl8ypUcE\"><meta itemprop=\"name\" content=\"Ascent\"><meta itemprop=\"description\" content=\"YouTube video\"><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/L9AKl8ypUcE\/0.jpg\"><meta itemprop=\"duration\" content=\"PT49S\"><meta itemprop=\"uploadDate\" content=\"2022-11-12T03:28:05Z\"><\/span>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">De spirituele groei is het doel van je leven en het perfectioneren ervan, jouw taak.<\/div><\/div>\n<p>Alle schatten van ware kennis van Sahaja Yoga zijn te vinden in de duizenden lezingen die Shri Mataji Nirmala Devi heeft gegeven. Elk van deze lezingen helpt ons de prachtige dimensies van ons spirituele bestaan te ontdekken en de juiste begeleiding te vinden om in dit bewustzijn te groeien. We raden onze lezers aan om actief de verschillende lezingen te volgen die je kunt vinden onder de secties <a href=\"https:\/\/shrimataji.org\/test\/nl\/publieke-programmas\/\" target=\"_blank\" rel=\"noopener\"><u>Publieke Programma&#8217;s<\/u><\/a> en\u00a0<a href=\"https:\/\/shrimataji.org\/test\/nl\/bibliotheek\/\" target=\"_blank\" rel=\"noopener\"><u>Bibliotheek<\/u><\/a>.<\/p>\n<p>Hier delen we zo&#8217;n mooie lezing over <a href=\"https:\/\/shrimataji.org\/test\/nl\/onze-spirituele-groei\/\" target=\"_blank\" rel=\"noopener\"><u>Onze Spirituele Groei<\/u><\/a> om onze spirituele meditatieve staat te verdiepen.<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Spirituele groei De illusies van het leven overstijgen Het belangrijkste doel van zelfrealisatie is het bereiken van een perfecte staat van evenwicht waarin we voortdurend kunnen opstijgen naar hogere bewustzijnsgebieden. Sahaja Yoga meditatie helpt ons om grote hoogten in ons spirituele bewustzijn te bereiken, waarvan de voordelen worden weerspiegeld in ons dagelijks leven, gezin, werk&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/\">Read more<\/a><\/p>\n","protected":false},"author":37,"featured_media":16525,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","advanced-sidebar-menu\/link-title":"","advanced-sidebar-menu\/exclude-page":false},"class_list":["post-16523","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spirituele groei - TEST - SMND<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spirituele groei - TEST - SMND\" \/>\n<meta property=\"og:description\" content=\"Spirituele groei De illusies van het leven overstijgen Het belangrijkste doel van zelfrealisatie is het bereiken van een perfecte staat van evenwicht waarin we voortdurend kunnen opstijgen naar hogere bewustzijnsgebieden. Sahaja Yoga meditatie helpt ons om grote hoogten in ons spirituele bewustzijn te bereiken, waarvan de voordelen worden weerspiegeld in ons dagelijks leven, gezin, werk&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/\" \/>\n<meta property=\"og:site_name\" content=\"TEST - SMND\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shrimataji\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T10:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/27_Banner-SY-Ascent-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@shrimataji\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/\",\"name\":\"Spirituele groei - TEST - SMND\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/27_Banner-SY-Ascent-scaled.jpg\",\"datePublished\":\"2022-01-29T09:56:43+00:00\",\"dateModified\":\"2025-11-19T10:42:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/27_Banner-SY-Ascent-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/27_Banner-SY-Ascent-scaled.jpg\",\"width\":2560,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/nl\\\/spirituele-groei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/uk\\\/home-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spirituele groei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#website\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/\",\"name\":\"Shri Mataji Nirmala Devi\",\"description\":\"A Life Dedicated to Humanity\",\"publisher\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/#\\\/schema\\\/person\\\/a1b3419c6585f164aa96da1ff85715d1\",\"name\":\"Nirmala Shrivastava\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"url\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"contentUrl\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nirmala Shrivastava\"},\"logo\":{\"@id\":\"https:\\\/\\\/shrimataji.org\\\/test\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SMO_LOGO-03.svg\"},\"sameAs\":[\"https:\\\/\\\/shrimataji.org\\\/test\",\"https:\\\/\\\/www.facebook.com\\\/shrimataji\",\"https:\\\/\\\/x.com\\\/shrimataji\",\"https:\\\/\\\/www.youtube.com\\\/@Shri_Mataji_Nirmala_Devi\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spirituele groei - TEST - SMND","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Spirituele groei - TEST - SMND","og_description":"Spirituele groei De illusies van het leven overstijgen Het belangrijkste doel van zelfrealisatie is het bereiken van een perfecte staat van evenwicht waarin we voortdurend kunnen opstijgen naar hogere bewustzijnsgebieden. Sahaja Yoga meditatie helpt ons om grote hoogten in ons spirituele bewustzijn te bereiken, waarvan de voordelen worden weerspiegeld in ons dagelijks leven, gezin, werk&hellip; Read more","og_url":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/","og_site_name":"TEST - SMND","article_publisher":"https:\/\/www.facebook.com\/shrimataji","article_modified_time":"2025-11-19T10:42:34+00:00","og_image":[{"width":2560,"height":905,"url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/27_Banner-SY-Ascent-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@shrimataji","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/","url":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/","name":"Spirituele groei - TEST - SMND","isPartOf":{"@id":"https:\/\/shrimataji.org\/test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/#primaryimage"},"image":{"@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/#primaryimage"},"thumbnailUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/27_Banner-SY-Ascent-scaled.jpg","datePublished":"2022-01-29T09:56:43+00:00","dateModified":"2025-11-19T10:42:34+00:00","breadcrumb":{"@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/#primaryimage","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/27_Banner-SY-Ascent-scaled.jpg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/03\/27_Banner-SY-Ascent-scaled.jpg","width":2560,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/shrimataji.org\/test\/nl\/spirituele-groei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shrimataji.org\/test\/uk\/home-en\/"},{"@type":"ListItem","position":2,"name":"Spirituele groei"}]},{"@type":"WebSite","@id":"https:\/\/shrimataji.org\/test\/#website","url":"https:\/\/shrimataji.org\/test\/","name":"Shri Mataji Nirmala Devi","description":"A Life Dedicated to Humanity","publisher":{"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shrimataji.org\/test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/shrimataji.org\/test\/#\/schema\/person\/a1b3419c6585f164aa96da1ff85715d1","name":"Nirmala Shrivastava","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","url":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","contentUrl":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg","width":"1024","height":"1024","caption":"Nirmala Shrivastava"},"logo":{"@id":"https:\/\/shrimataji.org\/test\/wp-content\/uploads\/2023\/02\/SMO_LOGO-03.svg"},"sameAs":["https:\/\/shrimataji.org\/test","https:\/\/www.facebook.com\/shrimataji","https:\/\/x.com\/shrimataji","https:\/\/www.youtube.com\/@Shri_Mataji_Nirmala_Devi\/featured"]}]}},"lang":"nl","translations":{"nl":16523,"ur":37391,"en":6391,"am":17962,"th":19888,"hu":19437,"sq":18363,"zh":17260,"hi":7355,"tr":10133,"pt":10350,"de":10623,"fr":10721,"it":10819,"es":10917,"ja":11214,"ru":11402,"bn":11594,"te":11702,"sw":11825,"he":11973,"el":12264,"sk":12362,"fa":12460,"fi":12558,"bg":13397,"ro":14471,"cs":14664,"ku":16683,"ar":16859,"be":18570,"kn":18844,"mr":20252,"uk":20544,"ml":20843,"ta":22678,"sv":22951,"gu":28799,"pa":28957,"fil":29397,"da":37705,"pl":37922,"nn":38257},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/16523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/comments?post=16523"}],"version-history":[{"count":0,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/pages\/16523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media\/16525"}],"wp:attachment":[{"href":"https:\/\/shrimataji.org\/test\/wp-json\/wp\/v2\/media?parent=16523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}